{"id":4479,"date":"2024-02-22T21:31:55","date_gmt":"2024-02-22T20:31:55","guid":{"rendered":"https:\/\/begegnungszentrum.ch\/?post_type=kultur&#038;p=4479"},"modified":"2024-02-22T21:32:25","modified_gmt":"2024-02-22T20:32:25","slug":"bierokratie-mit-dem-alcomedian-lukas-fehr","status":"publish","type":"kultur","link":"https:\/\/begegnungszentrum.ch\/en\/kultur\/bierokratie-mit-dem-alcomedian-lukas-fehr\/","title":{"rendered":"Beerocracy with the Alcomedian Lukas Fehr"},"content":{"rendered":"<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/begegnungszentrum.ch\/wp-content\/uploads\/2024\/02\/image-1.png\" alt=\"\" class=\"wp-image-4481\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Urauff\u00fchrung im Begegnungszentrum! \u00abBier auf Wein lass lieber sein\u00bb sagt der Volksmund. Der Alcomedian Lukas Fehr aus Buchberg weiss es besser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr ihn ist Schaumbildung auch eine Bildung. Deshalb wechselt er vom Barrique zum Bierfass. Aus besten gem\u00e4lzten Fakten und edlem Humorhopfen braut der Drogendealer unter den Verkaufsberatern &#8211; nat\u00fcrlich nicht allzu streng nach dem Reinheitsgebot &#8211; ein richtiges Bier-cherm\u00fcesli aus Witz und Wissen. Ob ober, unter, hinter, oder vorderg\u00e4rig \u2013 der Alcomedian setzt allem die Schaumkrone auf. Hier geht weder Hopfen noch Malz verloren. Sie werden sich k\u00f6stlich am\u00fcsieren \u2013 und k\u00f6nnen auch ein Glas Wein trinken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vorstellung und 4-Gang-Men\u00fc CHF 75.00, Mitglieder CHF 65.00<\/p>","protected":false},"excerpt":{"rendered":"<p>Eine Urauff\u00fchrung im Begegnungszentrum! \u00abBier auf Wein lass lieber sein\u00bb sagt der Volksmund. Der Alcomedian Lukas Fehr aus Buchberg weiss es besser. F\u00fcr ihn ist Schaumbildung auch eine Bildung. Deshalb wechselt er vom Barrique zum Bierfass. Aus besten gem\u00e4lzten Fakten und edlem Humorhopfen braut der Drogendealer unter den Verkaufsberatern &#8211; nat\u00fcrlich nicht allzu streng nach [&hellip;]<\/p>\n","protected":false},"featured_media":4482,"template":"","class_list":["post-4479","kultur","type-kultur","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/kultur\/4479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/kultur"}],"about":[{"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/types\/kultur"}],"version-history":[{"count":0,"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/kultur\/4479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/media\/4482"}],"wp:attachment":[{"href":"https:\/\/begegnungszentrum.ch\/en\/wp-json\/wp\/v2\/media?parent=4479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}